{"id":22,"count":19,"description":"","link":"https:\/\/nodosolidale.noblogs.org\/en-GB\/category\/militarizzazione-e-criminalita-organizzata\/","name":"Militarizzazione e Criminalit\u00e0 Organizzata","slug":"militarizzazione-e-criminalita-organizzata","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/nodosolidale.noblogs.org\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodosolidale.noblogs.org\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/nodosolidale.noblogs.org\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/nodosolidale.noblogs.org\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}